{"id":2964,"date":"2025-09-01T16:33:00","date_gmt":"2025-09-01T14:33:00","guid":{"rendered":"http:\/\/wordpress.p671235.webspaceconfig.de\/?p=2964"},"modified":"2025-10-28T10:11:51","modified_gmt":"2025-10-28T09:11:51","slug":"esg-nachhaltigkeitsrisiken","status":"publish","type":"post","link":"https:\/\/www.tbfsam.com\/en\/esg-nachhaltigkeitsrisiken\/","title":{"rendered":"ESG-Nachhaltigkeitsrisiken"},"content":{"rendered":"<p><strong>Offenlegungspflichten der TBF Global Asset Management GmbH gem\u00e4\u00df Artikel 3, Artikel 4 und Artikel 5 der Verordnung (EU) 2019\/2088 <\/strong><\/p>\n\n\n\n<p><strong>Nachhaltigkeitsrisiken der TBF Global Asset Management GmbH (nachfolgend TBF genannt) <\/strong><\/p>\n\n\n\n<p>Unter dem Begriff \u201eNachhaltigkeitsrisiken\u201c sind Ereignisse oder Bedingungen aus den Bereichen Umwelt, Soziales oder Unternehmensf\u00fchrung zusammengefasst, deren Eintreten tats\u00e4chlich oder potenziell wesentliche negative Auswirkungen auf unser Unternehmen und\/oder auf den Wert oder die Rendite der von uns verwalteten Investmentverm\u00f6gen und Direktanlagen haben k\u00f6nnte.<br><br>Nachhaltigkeitsrisiken k\u00f6nnen aber auch Einfluss auf andere bekannte Risikoarten haben und als ein Faktor zur Wesentlichkeit dieser Risikoarten beitragen. Daher betrachtet TBF in ihrem Risikomanagementsystem Nachhaltigkeitsrisiken als Teilfaktor anderer Risikoarten, insbesondere von Markt-, Preis\u00e4nderung-, Adressausfall- und Reputationsrisiken. Ob und in welchem Umfang Nachhaltigkeitsrisiken die Investitionsentscheidungen im Rahmen des Portfoliomanagements<br>beeinflussen, h\u00e4ngt wesentlich von der Anlagestrategie des einzelnen Fonds oder Portfolios ab. Je nach Assetklasse und der geltenden Anlagebedingungen kommen folgende Methoden in Betracht, um Nachhaltigkeitsrisiken zu reduzieren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Integration von (E)nvironmental-, (S)ocial-, und (G)overnance- Daten in den gesamten Investmentprozess. <\/li>\n\n\n\n<li>Ausschluss bestimmter Unternehmen, Wirtschaftszweige oder Regionen aus dem erwerbbaren Anlageuniversum. <\/li>\n\n\n\n<li>Auswahl von erwerbbaren Verm\u00f6gensgegenst\u00e4nden anhand einer fundamentalen ESG-Analyse und entsprechenden ESG-Kennzahlen sowie anschlie\u00dfende Kombination mit der finanziellen Analyse. <\/li>\n\n\n\n<li>Aktives Engagement mit Emittenten, wo n\u00f6tig, um eine positive Ver\u00e4nderung zu bewirken oder um weiteres Reporting einzufordern. <\/li>\n\n\n\n<li>Wahrnehmung der Stimmrechte erfolgt \u00fcber die Kapitalverwaltungsgesellschaften, um auch hier entsprechenden Einfluss zu nehmen und Nachhaltigkeitsrisiken, wenn m\u00f6glich, zu verringern. <\/li>\n<\/ul>\n\n\n\n<p>Weitere Informationen: https:\/\/www.hansainvest.de\/unternehmen\/compliance\/abstimmungsverhalten-bei-hauptversammlungen<\/p>\n\n\n\n<p><strong>Nachteilige Auswirkungen auf Nachhaltigkeitsfaktoren <\/strong><\/p>\n\n\n\n<p>TBF ber\u00fccksichtigt im Rahmen des Portfoliomanagements von Investmentsonderverm\u00f6gen derzeit noch nicht umfassend und systematisch etwaige nachteilige Auswirkungen von Investitionsentscheidungen auf Nachhaltigkeitsfaktoren. Unter Nachhaltigkeitsfaktoren versteht TBF in diesem Zusammenhang Umwelt-, Sozial- und Arbeitnehmerbelange, die Achtung der Menschenrechte und die Bek\u00e4mpfung von Korruption und Bestechung. Die gesetzlichen Anforderungen an die Messung und Gewichtung nachteiliger Nachhaltigkeitsauswirkungen sind neu und sehr detailliert. Die sorgf\u00e4ltige Umsetzung der regulatorischen Anforderungen erfordert einen erheblichen Aufwand, den wir derzeit nicht in ausreichendem Ma\u00dfe leisten k\u00f6nnen. Zudem sind bereits weitere \u00c4nderungen der regulatorischen Anforderungen angek\u00fcndigt, so dass uns die Etablierung entsprechender Prozesse derzeit nicht sinnvoll erscheint. Allerdings verwaltet unser Unternehmen einzelne Portfolien, bei denen die Ber\u00fccksichtigung nachteiliger Auswirkungen von Investitionsentscheidungen auf Nachhaltigkeitsfaktoren verbindlich festgelegter Teil der Anlagestrategie ist. Diese Fonds bewerben entweder \u00f6kologische und\/oder soziale Merkmale als Teil ihrer Anlagepolitik, oder streben nachhaltige Investitionen im Sinne der Verordnung (EU) 2019\/2088 an. Gem\u00e4\u00df der eben genannten Verordnung informieren wir in den vorvertraglichen Informationen, in den Jahresberichten und auf unserer Homepage f\u00fcr jeden dieser Fonds \u00fcber die festgelegten Merkmale oder Nach- haltigkeitsziele sowie dar\u00fcber, ob und ggf. wie die Ber\u00fccksichtigung nachteiliger Nachhaltigkeitsauswirkungen Bestandteil der Anlagestrategie ist. <\/p>\n\n\n\n<p><strong>Ber\u00fccksichtigung von Nachhaltigkeitsrisiken in der Verg\u00fctungspolitik <\/strong><\/p>\n\n\n\n<p>Gem. Art. 5 der Verordnung (EU) 2019\/2088 muss TBF angeben, inwiefern die Verg\u00fctungspolitik mit der Einbeziehung von Nachhaltigkeitsrisiken in Einklang steht. Die Befassung mit, beziehungsweise Verringerung von Nachhaltigkeitsrisiken auf Unternehmensebene oder auf Ebene einzelner Fonds wird im Rahmen des Verg\u00fctungssystems nicht gesondert ber\u00fccksichtigt. Diese Aspekte k\u00f6nnen die Verg\u00fctungspolitik und -praxis lediglich als Teil der allgemeinen Risikostrategie, oder als Teil von individuellen Zielvereinbarungen mittelbar beeinflussen.<\/p>\n\n\n\n<p><strong>Erl\u00e4uterung wesentlicher \u00c4nderungen des vorliegenden Dokuments <\/strong><\/p>\n\n\n\n<p>Wir sind verpflichtet, wesentliche \u00c4nderungen an der vorliegenden Offenlegung explizit zu erl\u00e4utern und kommen dieser Vorgabe in folgender Tabelle nach:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Version<\/td><td>Datum<\/td><td>\u00c4nderung<\/td><\/tr><tr><td>1<\/td><td>03.2021<\/td><td>&#8211;<\/td><\/tr><tr><td>2<\/td><td>09.2022<\/td><td>Anpassungen aufgrund ge\u00e4nderter interner Prozesse<\/td><\/tr><tr><td>3<\/td><td>11.2023<\/td><td>Anpassungen aufgrund ge\u00e4nderter interner Prozesse<\/td><\/tr><tr><td>4<\/td><td>10.2024<\/td><td>&#8211;<\/td><\/tr><tr><td>5<\/td><td>09.2025<\/td><td>&#8211;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Offenlegungspflichten der TBF Global Asset Management GmbH gem\u00e4\u00df Artikel 3, Artikel 4 und Artikel 5 der Verordnung (EU) 2019\/2088 Nachhaltigkeitsrisiken der TBF Global Asset Management GmbH (nachfolgend TBF genannt) Unter dem Begriff \u201eNachhaltigkeitsrisiken\u201c sind Ereignisse oder Bedingungen aus den Bereichen Umwelt, Soziales oder Unternehmensf\u00fchrung zusammengefasst, deren Eintreten tats\u00e4chlich oder potenziell wesentliche negative Auswirkungen auf unser [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"categories":[34,36],"tags":[],"class_list":["post-2964","post","type-post","status-publish","format-standard","hentry","category-alle-transparenzen","category-esg-policies"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:05:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/posts\/2964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/comments?post=2964"}],"version-history":[{"count":3,"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/posts\/2964\/revisions"}],"predecessor-version":[{"id":6202,"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/posts\/2964\/revisions\/6202"}],"wp:attachment":[{"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/media?parent=2964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/categories?post=2964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tbfsam.com\/en\/wp-json\/wp\/v2\/tags?post=2964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}